{"id":818,"date":"2015-07-25T03:41:06","date_gmt":"2015-07-25T01:41:06","guid":{"rendered":"http:\/\/le-bars.net\/yoann\/?p=818"},"modified":"2015-09-16T12:49:33","modified_gmt":"2015-09-16T10:49:33","slug":"epilogue-au-projet-de-loi-sur-le-renseignement","status":"publish","type":"post","link":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/","title":{"rendered":"\u00c9pilogue au projet de loi sur le renseignement"},"content":{"rendered":"<p>Le jeudi 23 juillet 2015, <a href=\"http:\/\/www.lemonde.fr\/pixels\/article\/2015\/07\/23\/le-conseil-constitutionnel-censure-trois-articles-de-la-loi-sur-le-renseignement_4696112_4408996.html\" title=\"Validation de la loi sur le renseignement\" target=\"_blank\">le Conseil constitutionnel a avalis\u00e9 l\u2019essentiel de la loi sur le renseignement<\/a>. Dans la foul\u00e9e, <a href=\"http:\/\/www.lemonde.fr\/pixels\/article\/2015\/07\/24\/la-loi-de-programmation-militaire-jugee-conforme-au-droit-au-respect-de-la-vie-privee_4697006_4408996.html\" title=\"Validation de la loi de programmation militaire\" target=\"_blank\">il a jug\u00e9 conforme \u00e0 la protection de la vie priv\u00e9e le volet de la loi de programmation militaire concernant la surveillance sur Internet<\/a>. Pourtant, quelques heures auparavant, le Comit\u00e9 des droits de l\u2019homme de l\u2019ONU avait \u00e9mis des inqui\u00e9tudes concernant la loi sur le renseignement.<\/p>\n<p>Trois articles ont \u00e9t\u00e9 censur\u00e9s, mais l\u2019essentiel de la loi est pass\u00e9e. Notamment, les bo\u00eetes noires ont \u00e9t\u00e9 valid\u00e9es, en d\u00e9pit des interrogations qu\u2019elles suscitent.<\/p>\n<p>Voici l\u2019\u00e9pilogue pour <a href=\"http:\/\/le-bars.net\/yoann\/fr\/2015\/04\/14\/tout-va-bien-le-premier-ministre-veille\/\" title=\"Premier article\">un sujet<\/a> <a href=\"http:\/\/le-bars.net\/yoann\/fr\/2015\/04\/21\/ce-nest-pas-le-nombre-qui-compte\/\" title=\"Deuxi\u00e8me article\">plusieurs fois<\/a> <a href=\"http:\/\/le-bars.net\/yoann\/fr\/2015\/06\/18\/un-point-sur-le-projet-de-loi-sur-le-renseignement\/\" title=\"Troisi\u00e8me article\">abord\u00e9 dans ce journal<\/a>. Cela dit, une prochaine loi pourra toujours am\u00e9liorer les \u00e9quilibres dans la loi. Esp\u00e9rons que ce sera le cas, en se basant sur un examen rigoureux des cons\u00e9quences qu\u2019aura la loi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le jeudi 23 juillet 2015, le Conseil constitutionnel a avalis\u00e9 l\u2019essentiel de la loi sur le renseignement. Dans la foul\u00e9e, il a jug\u00e9 conforme \u00e0 la protection de la vie priv\u00e9e le volet de la loi de programmation militaire concernant la surveillance sur Internet. Pourtant, quelques heures auparavant, le Comit\u00e9 des droits de l\u2019homme de &hellip; <a href=\"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">\u00c9pilogue au projet de loi sur le renseignement<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15],"tags":[34,36],"class_list":["post-818","post","type-post","status-publish","format-aside","hentry","category-politique","tag-libertes-individuelles","tag-surveillance","post_format-post-format-aside"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici<\/title>\n<meta name=\"description\" content=\"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici\" \/>\n<meta property=\"og:description\" content=\"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/\" \/>\n<meta property=\"og:site_name\" content=\"Vu d\u2019ici\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-25T01:41:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-16T10:49:33+00:00\" \/>\n<meta name=\"author\" content=\"Yoann Le Bars\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yoann Le Bars\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/\"},\"author\":{\"name\":\"Yoann Le Bars\",\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#\\\/schema\\\/person\\\/90c5a2de7ad2db1184bbe140ebea1576\"},\"headline\":\"\u00c9pilogue au projet de loi sur le renseignement\",\"datePublished\":\"2015-07-25T01:41:06+00:00\",\"dateModified\":\"2015-09-16T10:49:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/\"},\"wordCount\":156,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#\\\/schema\\\/person\\\/90c5a2de7ad2db1184bbe140ebea1576\"},\"keywords\":[\"Libert\u00e9s individuelles\",\"Surveillance\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/\",\"url\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/\",\"name\":\"\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#website\"},\"datePublished\":\"2015-07-25T01:41:06+00:00\",\"dateModified\":\"2015-09-16T10:49:33+00:00\",\"description\":\"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/2015\\\/07\\\/25\\\/epilogue-au-projet-de-loi-sur-le-renseignement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9pilogue au projet de loi sur le renseignement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#website\",\"url\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/\",\"name\":\"Vu d\u2019ici\",\"description\":\"Pages personnelles de Yoann LE\u00a0BARS\",\"publisher\":{\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#\\\/schema\\\/person\\\/90c5a2de7ad2db1184bbe140ebea1576\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/le-bars.net\\\/yoann\\\/#\\\/schema\\\/person\\\/90c5a2de7ad2db1184bbe140ebea1576\",\"name\":\"Yoann Le Bars\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/le-bars.net\\\/yoann\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/le-bars.net\\\/yoann\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/le-bars.net\\\/yoann\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1\",\"width\":80,\"height\":80,\"caption\":\"Yoann Le Bars\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/le-bars.net\\\/yoann\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1\"},\"description\":\"Un enseignant-chercheur avec un peu trop de centres d\u2019int\u00e9r\u00eats pour pouvoir r\u00e9sumer\u2026\",\"sameAs\":[\"http:\\\/\\\/le-bars.net\\\/yoann\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici","description":"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici","og_description":"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.","og_url":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/","og_site_name":"Vu d\u2019ici","article_published_time":"2015-07-25T01:41:06+00:00","article_modified_time":"2015-09-16T10:49:33+00:00","author":"Yoann Le Bars","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Yoann Le Bars","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/#article","isPartOf":{"@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/"},"author":{"name":"Yoann Le Bars","@id":"https:\/\/le-bars.net\/yoann\/#\/schema\/person\/90c5a2de7ad2db1184bbe140ebea1576"},"headline":"\u00c9pilogue au projet de loi sur le renseignement","datePublished":"2015-07-25T01:41:06+00:00","dateModified":"2015-09-16T10:49:33+00:00","mainEntityOfPage":{"@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/"},"wordCount":156,"commentCount":1,"publisher":{"@id":"https:\/\/le-bars.net\/yoann\/#\/schema\/person\/90c5a2de7ad2db1184bbe140ebea1576"},"keywords":["Libert\u00e9s individuelles","Surveillance"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/","url":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/","name":"\u00c9pilogue au projet de loi sur le renseignement &#8211; Vu d\u2019ici","isPartOf":{"@id":"https:\/\/le-bars.net\/yoann\/#website"},"datePublished":"2015-07-25T01:41:06+00:00","dateModified":"2015-09-16T10:49:33+00:00","description":"La loi sur le renseignement a finalement \u00e9t\u00e9 accept\u00e9e.","breadcrumb":{"@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/le-bars.net\/yoann\/fr\/2015\/07\/25\/epilogue-au-projet-de-loi-sur-le-renseignement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/le-bars.net\/yoann\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9pilogue au projet de loi sur le renseignement"}]},{"@type":"WebSite","@id":"https:\/\/le-bars.net\/yoann\/#website","url":"https:\/\/le-bars.net\/yoann\/","name":"Vu d\u2019ici","description":"Pages personnelles de Yoann LE\u00a0BARS","publisher":{"@id":"https:\/\/le-bars.net\/yoann\/#\/schema\/person\/90c5a2de7ad2db1184bbe140ebea1576"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/le-bars.net\/yoann\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/le-bars.net\/yoann\/#\/schema\/person\/90c5a2de7ad2db1184bbe140ebea1576","name":"Yoann Le Bars","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/i0.wp.com\/le-bars.net\/yoann\/wordpress\/wp-content\/uploads\/2020\/11\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1","url":"https:\/\/i0.wp.com\/le-bars.net\/yoann\/wordpress\/wp-content\/uploads\/2020\/11\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1","contentUrl":"https:\/\/i0.wp.com\/le-bars.net\/yoann\/wordpress\/wp-content\/uploads\/2020\/11\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1","width":80,"height":80,"caption":"Yoann Le Bars"},"logo":{"@id":"https:\/\/i0.wp.com\/le-bars.net\/yoann\/wordpress\/wp-content\/uploads\/2020\/11\/fec731577f2c05141910be0dc3ef5bb2.jpeg?fit=80%2C80&ssl=1"},"description":"Un enseignant-chercheur avec un peu trop de centres d\u2019int\u00e9r\u00eats pour pouvoir r\u00e9sumer\u2026","sameAs":["http:\/\/le-bars.net\/yoann"]}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p61hos-dc","jetpack-related-posts":[{"id":317,"url":"https:\/\/le-bars.net\/yoann\/fr\/2015\/06\/18\/un-point-sur-le-projet-de-loi-sur-le-renseignement\/","url_meta":{"origin":818,"position":0},"title":"Un point sur le projet de loi sur le renseignement","author":"Yoann Le Bars","date":"18 juin 2015","format":false,"excerpt":"Le projet de loi sur le renseignement, que j\u2019ai d\u00e9j\u00e0 mentionn\u00e9 par ici et par l\u00e0, a \u00e9t\u00e9 massivement approuv\u00e9 par l\u2019Assembl\u00e9e nationale ainsi que par le S\u00e9nat. Ceci en d\u00e9pit du fait que l\u2019INRIA a produit une note tr\u00e8s critique \u00e0 son \u00e9gard, ajoutant \u00e0 la longue liste des\u2026","rel":"","context":"Dans &quot;Politique&quot;","block_context":{"text":"Politique","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/politique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2112,"url":"https:\/\/le-bars.net\/yoann\/fr\/2016\/01\/29\/un-peu-de-statistique-evaluer-la-loi-sur-le-renseignement\/","url_meta":{"origin":818,"position":1},"title":"Analyse statistique de la loi sur le renseignement","author":"Yoann Le Bars","date":"29 janvier 2016","format":false,"excerpt":"Il n\u2019aura \u00e9chapp\u00e9 \u00e0 personne que le d\u00e9bat public, au moins en France, est domin\u00e9 ces derniers temps par les questions de s\u00e9curit\u00e9s. Les attentats \u00e0 Paris le 13\u00a0novembre\u00a02015 ont particip\u00e9 \u00e0 mettre ces questions sur le devant de la sc\u00e8ne. Pourtant, si la n\u00e9cessit\u00e9 d\u2019agir, probablement av\u00e9r\u00e9e, est souvent\u2026","rel":"","context":"Dans &quot;Point de vue&quot;","block_context":{"text":"Point de vue","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/point-de-vue\/"},"img":{"alt_text":"Edward\u00a0Sowden en 2013","src":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/60\/Edward_Snowden-2.jpg","width":350,"height":200,"srcset":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/60\/Edward_Snowden-2.jpg 1x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/60\/Edward_Snowden-2.jpg 1.5x"},"classes":[]},{"id":118,"url":"https:\/\/le-bars.net\/yoann\/fr\/2015\/04\/14\/tout-va-bien-le-premier-ministre-veille\/","url_meta":{"origin":818,"position":2},"title":"Tout va bien, le premier ministre veille\u202f!","author":"Yoann Le Bars","date":"14 avril 2015","format":false,"excerpt":"Nous autres, Fran\u00e7ais, que n\u2019avons-nous pas manqu\u00e9 de moquer les \u00c9tats-Unis, qui, suite au 11 septembre 2001, ont sombr\u00e9 dans une politique de surveillance tous azimuts. Fort heureusement, les Fran\u00e7ais, bien plus intelligents que les Am\u00e9ricains, sont immunis\u00e9s \u00e0 ce genre de travers. Les r\u00e9actions politiques aux attaques terroristes du\u2026","rel":"","context":"Dans &quot;Politique&quot;","block_context":{"text":"Politique","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/politique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":205,"url":"https:\/\/le-bars.net\/yoann\/fr\/2015\/04\/21\/ce-nest-pas-le-nombre-qui-compte\/","url_meta":{"origin":818,"position":3},"title":"Ce n\u2019est pas le nombre qui compte\u202f?","author":"Yoann Le Bars","date":"21 avril 2015","format":false,"excerpt":"La loi sur le renseignement, dont j\u2019ai d\u00e9j\u00e0 parl\u00e9 par ici, a \u00e9t\u00e9 approuv\u00e9e par 25 d\u00e9put\u00e9s fran\u00e7ais, tandis que cinq s\u2019y sont oppos\u00e9s. Ils \u00e9taient donc 30 pr\u00e9sents pour voter une loi qui touche aux libert\u00e9s individuelles. 30 sur une l\u00e9gislature comptant 577 d\u00e9put\u00e9s. C\u2019est-\u00e0-dire qu\u2019environ 5\u202f% des d\u00e9put\u00e9s\u2026","rel":"","context":"Dans &quot;Politique&quot;","block_context":{"text":"Politique","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/politique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5601,"url":"https:\/\/le-bars.net\/yoann\/fr\/2024\/12\/01\/macaron-cassis-violette-saison-2-episode-2-sauvons-la-reforme-des-retraites\/","url_meta":{"origin":818,"position":4},"title":"Macaron Cassis Violette \u2013 Saison 2, \u00e9pisode 2\u00a0: Sauvons la r\u00e9forme des retraites\u202f!","author":"Yoann Le Bars","date":"1 d\u00e9cembre 2024","format":false,"excerpt":"https:\/\/vimeo.com\/1034896583?share=copy#t=0 Macaron Cassis Violette \u2013 Saison 2, \u00e9pisode 2\u00a0: Sauvons la r\u00e9forme des retraites\u202f! Deuxi\u00e8me \u00e9pisode de la saison 2 de Macarons Cassis Violette, diffus\u00e9 initialement sur la cha\u00eene Twitch de la Sorcenouille lors de la Revue\u00a0de\u00a0presse\u00a0des\u00a0chapoules du 4\u00a0novembre\u00a02024. Les Ministres De\u00a0Tout et Du\u00a0Reste sont en \u00e9moi, le Rassemblement\u00a0National a\u2026","rel":"","context":"Dans &quot;Culture&quot;","block_context":{"text":"Culture","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/culture\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1199,"url":"https:\/\/le-bars.net\/yoann\/fr\/2016\/07\/28\/vie-privee-une-anomalie-bientot-corrigee\/","url_meta":{"origin":818,"position":5},"title":"La vie priv\u00e9e\u00a0: une anomalie bient\u00f4t corrig\u00e9e","author":"Yoann Le Bars","date":"28 juillet 2016","format":false,"excerpt":"Vinton\u00a0Cerf a eu un r\u00f4le essentiel pour les syst\u00e8mes de communications modernes\u00a0: il est l\u2019un des inventeurs du protocole TCP\/IP, qui est \u00e0 la base d\u2019Internet. Il est d\u00e9sormais chez Google, r\u00e9cemment devenu Alphabet. Le 20\u00a0novembre\u00a02013, il a d\u00e9clar\u00e9 que \u00ab\u202fla vie priv\u00e9e pourrait bien \u00eatre une anomalie\u202f\u00bb. Qu\u2019on se\u2026","rel":"","context":"Dans &quot;Point de vue&quot;","block_context":{"text":"Point de vue","link":"https:\/\/le-bars.net\/yoann\/fr\/category\/point-de-vue\/"},"img":{"alt_text":"Vinton Cerf","src":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg","width":350,"height":200,"srcset":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg 1x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg 1.5x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg 2x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg 3x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/bb\/Vint_Cerf_-_2010.jpg 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":9,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"predecessor-version":[{"id":1871,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/posts\/818\/revisions\/1871"}],"wp:attachment":[{"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/le-bars.net\/yoann\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}